{"id":780,"date":"2026-07-15T02:10:55","date_gmt":"2026-07-15T02:10:55","guid":{"rendered":"https:\/\/abicos.de\/cms\/?page_id=780"},"modified":"2026-07-15T03:10:55","modified_gmt":"2026-07-15T02:10:55","slug":"agb","status":"publish","type":"page","link":"https:\/\/abicos.de\/cms\/agb\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen mit Kundeninformationen"},"content":{"rendered":"<div  class=\"agb_content agb_terms  notranslate\"><div><h2>Inhaltsverzeichnis<\/h2>\n<ol>\n<li>Geltungsbereich<\/li>\n<li>Vertragsschluss<\/li>\n<li>Widerrufsrecht<\/li>\n<li>Preise und Zahlungsbedingungen<\/li>\n<li>Liefer- und Versandbedingungen<\/li>\n<li>Einr&auml;umung von Nutzungsrechten f&uuml;r digitale Inhalte<\/li>\n<li>Vertragsdauer und Vertragsbeendigung bei Abonnementvertr&auml;gen f&uuml;r Waren<\/li>\n<li>Vertragsdauer und Vertragsbeendigung bei Abonnementvertr&auml;gen f&uuml;r digitale Inhalte<\/li>\n<li>Eigentumsvorbehalt<\/li>\n<li>M&auml;ngelhaftung (Gew&auml;hrleistung)<\/li>\n<li>Haftung<\/li>\n<li>Besondere Bedingungen f&uuml;r die Verarbeitung von Waren nach bestimmten Vorgaben des Kunden<\/li>\n<li>Einl&ouml;sung von Aktionsgutscheinen<\/li>\n<li>Einl&ouml;sung von Geschenkgutscheinen<\/li>\n<li>Anwendbares Recht<\/li>\n<li>Verhaltenskodex<\/li>\n<li>Alternative Streitbeilegung<\/li>\n<\/ol>\n\n<h2>1) Geltungsbereich<\/h2>\n\n<p><b>1.1<\/b>&nbsp;Diese Allgemeinen Gesch&auml;ftsbedingungen (nachfolgend &bdquo;AGB&#8220;) des Andreas Bischof, handelnd unter &bdquo;ABICOS (Andreas Bischof Computer Systeme)&#8220; (nachfolgend &bdquo;Verk&auml;ufer&quot;), gelten f&uuml;r alle Vertr&auml;ge zur Lieferung von Waren, die ein Verbraucher oder Unternehmer (nachfolgend &bdquo;Kunde&#8220;) mit dem Verk&auml;ufer hinsichtlich der vom Verk&auml;ufer in seinem Online-Shop dargestellten Waren abschlie&szlig;t. Hiermit wird der Einbeziehung von eigenen Bedingungen des Kunden widersprochen, es sei denn, es ist etwas anderes vereinbart.<\/p>\n\n<p><b>1.2<\/b>&nbsp;F&uuml;r Vertr&auml;ge zur Lieferung von Waren mit digitalen Elementen gelten diese AGB entsprechend, sofern insoweit nicht etwas Abweichendes geregelt ist. Dabei schuldet der Verk&auml;ufer neben der Lieferung der Ware die Bereitstellung von digitalen Inhalten oder digitalen Dienstleistungen (nachfolgend &bdquo;digitale Produkte&#8220;), die in einer Weise in der Ware enthalten oder mit ihr verbunden sind, dass die Ware ihre Funktionen ohne sie nicht erf&uuml;llen kann.<\/p>\n\n<p><b>1.3<\/b>&nbsp;F&uuml;r Vertr&auml;ge zur Lieferung von k&ouml;rperlichen Datentr&auml;gern, die ausschlie&szlig;lich als Tr&auml;ger digitaler Inhalte dienen, gelten diese AGB entsprechend, sofern insoweit nicht etwas Abweichendes geregelt ist. Digitale Inhalte im Sinne dieser AGB sind Daten, die in digitaler Form erstellt und bereitgestellt werden.<\/p>\n\n<p><b>1.4<\/b>&nbsp;F&uuml;r Vertr&auml;ge zur Lieferung von Gutscheinen gelten diese AGB entsprechend, sofern insoweit nicht etwas Abweichendes geregelt ist.<\/p>\n\n<p><b>1.5<\/b>&nbsp;F&uuml;r Vertr&auml;ge zur Lieferung von Tickets gelten diese AGB entsprechend, sofern insoweit nicht ausdr&uuml;cklich etwas Abweichendes geregelt ist. Dabei regeln diese AGB lediglich den Verkauf von Tickets f&uuml;r bestimmte, in der Artikelbeschreibung des Verk&auml;ufers n&auml;her bezeichnete Veranstaltungen und nicht die Durchf&uuml;hrung dieser Veranstaltungen. F&uuml;r die Durchf&uuml;hrung der Veranstaltungen gelten ausschlie&szlig;lich die gesetzlichen Bestimmungen im Verh&auml;ltnis zwischen dem Teilnehmer und dem Veranstalter sowie ggf. hiervon abweichende Bedingungen des Veranstalters. Sofern der Verk&auml;ufer nicht zugleich auch Veranstalter ist, haftet er nicht f&uuml;r die ordnungsgem&auml;&szlig;e Durchf&uuml;hrung der Veranstaltung, f&uuml;r die ausschlie&szlig;lich der jeweilige Veranstalter verantwortlich ist.<\/p>\n\n<p><b>1.6<\/b>&nbsp;F&uuml;r Vertr&auml;ge zur Bereitstellung von digitalen Inhalten gelten diese AGB entsprechend, sofern insoweit nicht etwas Abweichendes geregelt ist. Digitale Inhalte im Sinne dieser AGB sind Daten, die in digitaler Form erstellt und bereitgestellt werden.<\/p>\n\n<p><b>1.7<\/b>&nbsp;Verbraucher im Sinne dieser AGB ist jede nat&uuml;rliche Person, die ein Rechtsgesch&auml;ft zu Zwecken abschlie&szlig;t, die &uuml;berwiegend weder ihrer gewerblichen noch ihrer selbst&auml;ndigen beruflichen T&auml;tigkeit zugerechnet werden k&ouml;nnen.<\/p>\n\n<p><b>1.8<\/b>&nbsp;Unternehmer im Sinne dieser AGB ist eine nat&uuml;rliche oder juristische Person oder eine rechtsf&auml;hige Personengesellschaft, die bei Abschluss eines Rechtsgesch&auml;fts in Aus&uuml;bung ihrer gewerblichen oder selbst&auml;ndigen beruflichen T&auml;tigkeit handelt.<\/p>\n\n<p><b>1.9<\/b>&nbsp;Gegenstand des Vertrages kann &ndash; je nach Produktbeschreibung des Verk&auml;ufers - sowohl der Bezug von Waren im Wege einer Einmallieferung als auch der Bezug von Waren im Wege einer dauerhaften Lieferung (nachfolgend &bdquo;Abonnementvertrag&#8220;) sein. Beim Abonnementvertrag verpflichtet sich der Verk&auml;ufer, dem Kunden die vertraglich geschuldete Ware f&uuml;r die Dauer der vereinbarten Vertragslaufzeit in den vertraglich geschuldeten Zeitintervallen zu liefern.<\/p>\n\n<p><b>1.10<\/b>&nbsp;Gegenstand des Vertrages kann &ndash; je nach Inhaltsbeschreibung des Verk&auml;ufers &ndash; sowohl die einmalige Bereitstellung von digitalen Inhalten, als auch die regelm&auml;&szlig;ige Bereitstellung von digitalen Inhalten (nachfolgend &bdquo;Abonnementvertrag&#8220;) sein. Beim Abonnementvertrag verpflichtet sich der Verk&auml;ufer, dem Kunden die vertraglich geschuldeten digitalen Inhalte f&uuml;r die Dauer der vereinbarten Vertragslaufzeit in den vertraglich vereinbarten Zeitintervallen bereitzustellen.<\/p>\n\n<p><b>1.11<\/b>&nbsp;Bestandteile des dargestellten Sortiments des Verk&auml;ufers k&ouml;nnen &ndash; je nach Produktbeschreibung des Verk&auml;ufers - mit dem Abschluss eines Vertrages &uuml;ber die Erbringung von Telekommunikationsdienstleistungen (nachfolgend &bdquo;Telekommunikationsvertrag&#8220;) mit einem Drittanbieter (nachfolgend &bdquo;Serviceprovider&#8220;) verbunden sein. In diesem Fall h&auml;ngt der Bestand des Vertrages mit dem Verk&auml;ufer vom Abschluss eines Telekommunikationsvertrages mit dem Serviceprovider und davon ab, dass der Telekommunikationsvertrag vom Kunden nicht widerrufen wird. F&uuml;r den Telekommunikationsvertrag gelten die entsprechenden gesetzlichen Bestimmungen sowie ggf. hiervon abweichende Vertragsbedingungen des jeweiligen Serviceproviders. Der Verk&auml;ufer tritt f&uuml;r solche Vertr&auml;ge lediglich als Vermittler auf.<\/p>\n\n<h2>2) Vertragsschluss<\/h2>\n\n<p><b>2.1<\/b>&nbsp;Die im Online-Shop des Verk&auml;ufers enthaltenen Produktbeschreibungen stellen keine verbindlichen Angebote seitens des Verk&auml;ufers dar, sondern dienen zur Abgabe eines verbindlichen Angebots durch den Kunden.<\/p>\n\n<p><b>2.2<\/b>&nbsp;Der Kunde kann das Angebot &uuml;ber das in den Online-Shop des Verk&auml;ufers integrierte Online-Bestellformular abgeben. Dabei gibt der Kunde, nachdem er die ausgew&auml;hlten Waren in den virtuellen Warenkorb gelegt und den elektronischen Bestellprozess durchlaufen hat, durch Klicken des den Bestellvorgang abschlie&szlig;enden Buttons ein rechtlich verbindliches Vertragsangebot in Bezug auf die im Warenkorb enthaltenen Waren ab. Ferner kann der Kunde das Angebot auch per E-Mail, per Fax, per Online-Kontaktformular, postalisch oder telefonisch gegen&uuml;ber dem Verk&auml;ufer abgeben.<\/p>\n\n<p><b>2.3<\/b>&nbsp;Der Verk&auml;ufer kann das Angebot des Kunden innerhalb von f&uuml;nf Tagen annehmen,<\/p>\n\n<ul>\n<li>indem er dem Kunden eine schriftliche Auftragsbest&auml;tigung oder eine Auftragsbest&auml;tigung in Textform (Fax oder E-Mail) &uuml;bermittelt, wobei insoweit der Zugang der Auftragsbest&auml;tigung beim Kunden ma&szlig;geblich ist, oder<\/li>\n<li>indem er dem Kunden die bestellte Ware liefert, wobei insoweit der Zugang der Ware beim Kunden ma&szlig;geblich ist, oder<\/li>\n<li>indem er den Kunden nach Abgabe von dessen Bestellung zur Zahlung auffordert.<\/li>\n<\/ul>\n\n<p>Liegen mehrere der vorgenannten Alternativen vor, kommt der Vertrag in dem Zeitpunkt zustande, in dem eine der vorgenannten Alternativen zuerst eintritt. Die Frist zur Annahme des Angebots beginnt am Tag nach der Absendung des Angebots durch den Kunden zu laufen und endet mit dem Ablauf des f&uuml;nften Tages, welcher auf die Absendung des Angebots folgt. Nimmt der Verk&auml;ufer das Angebot des Kunden innerhalb vorgenannter Frist nicht an, so gilt dies als Ablehnung des Angebots mit der Folge, dass der Kunde nicht mehr an seine Willenserkl&auml;rung gebunden ist.<\/p>\n\n<p><b>2.4<\/b>&nbsp;Bei Auswahl einer von PayPal angebotenen Zahlungsart erfolgt die Zahlungsabwicklung &uuml;ber den Zahlungsdienstleister PayPal (Europe) S.&agrave; r.l. et Cie, S.C.A., 22-24 Boulevard Royal, L-2449 Luxemburg (im Folgenden: &bdquo;PayPal&#8220;), unter Geltung der PayPal-Nutzungsbedingungen, einsehbar unter <a href=\"https:\/\/www.paypal.com\/de\/legalhub\/paypal\/useragreement-full\" target=\"_blank\">https:\/\/www.paypal.com<wbr>\/de<wbr>\/legalhub<wbr>\/paypal<wbr>\/useragreement-full<\/a> oder - falls der Kunde nicht &uuml;ber ein PayPal-Konto verf&uuml;gt &ndash; unter Geltung der Bedingungen f&uuml;r Zahlungen ohne PayPal-Konto, einsehbar unter <a href=\"https:\/\/www.paypal.com\/de\/legalhub\/paypal\/privacywax-full\" target=\"_blank\">https:\/\/www.paypal.com<wbr>\/de<wbr>\/legalhub<wbr>\/paypal<wbr>\/privacywax-full<\/a>. Zahlt der Kunde mittels einer im Online-Bestellvorgang ausw&auml;hlbaren von PayPal angebotenen Zahlungsart, erkl&auml;rt der Verk&auml;ufer schon jetzt die Annahme des Angebots des Kunden in dem Zeitpunkt, in dem der Kunde den Button anklickt, welcher den Bestellvorgang abschlie&szlig;t.<\/p>\n\n<p><b>2.5<\/b>&nbsp;Bei der Bestellung &uuml;ber das Online-Bestellformular des Verk&auml;ufers wird der Vertragstext nach dem Vertragsschluss vom Verk&auml;ufer gespeichert und dem Kunden nach Absendung von dessen Bestellung in Textform (z. B. E-Mail, Fax oder Brief) &uuml;bermittelt. Eine dar&uuml;ber hinausgehende Zug&auml;nglichmachung des Vertragstextes durch den Verk&auml;ufer erfolgt nicht. Sofern der Kunde vor Absendung seiner Bestellung ein Nutzerkonto im Online-Shop des Verk&auml;ufers eingerichtet hat, werden die Bestelldaten auf der Website des Verk&auml;ufers archiviert und k&ouml;nnen vom Kunden &uuml;ber dessen passwortgesch&uuml;tztes Nutzerkonto unter Angabe der entsprechenden Login-Daten kostenlos abgerufen werden.<\/p>\n\n<p><b>2.6<\/b>&nbsp;Vor verbindlicher Abgabe der Bestellung &uuml;ber das Online-Bestellformular des Verk&auml;ufers kann der Kunde m&ouml;gliche Eingabefehler durch aufmerksames Lesen der auf dem Bildschirm dargestellten Informationen erkennen. Ein wirksames technisches Mittel zur besseren Erkennung von Eingabefehlern kann dabei die Vergr&ouml;&szlig;erungsfunktion des Browsers sein, mit deren Hilfe die Darstellung auf dem Bildschirm vergr&ouml;&szlig;ert wird. Seine Eingaben kann der Kunde im Rahmen des elektronischen Bestellprozesses so lange &uuml;ber die &uuml;blichen Tastatur- und Mausfunktionen korrigieren, bis er den Button anklickt, welcher den Bestellvorgang abschlie&szlig;t.<\/p>\n\n<p><b>2.7<\/b>&nbsp;F&uuml;r den Vertragsschluss steht die deutsche Sprache zur Verf&uuml;gung.<\/p>\n\n<p><b>2.8<\/b>&nbsp;Die Bestellabwicklung und Kontaktaufnahme finden in der Regel per E-Mail und automatisierter Bestellabwicklung statt. Der Kunde hat sicherzustellen, dass die von ihm zur Bestellabwicklung angegebene E-Mail-Adresse zutreffend ist, so dass unter dieser Adresse die vom Verk&auml;ufer versandten E-Mails empfangen werden k&ouml;nnen. Insbesondere hat der Kunde bei dem Einsatz von SPAM-Filtern sicherzustellen, dass alle vom Verk&auml;ufer oder von diesem mit der Bestellabwicklung beauftragten Dritten versandten E-Mails zugestellt werden k&ouml;nnen.<\/p>\n\n<h2>3) Widerrufsrecht<\/h2>\n\n<p><b>3.1<\/b>&nbsp;Verbrauchern steht grunds&auml;tzlich ein Widerrufsrecht zu.<\/p>\n\n<p><b>3.2<\/b>&nbsp;N&auml;here Informationen zum Widerrufsrecht ergeben sich aus der Widerrufsbelehrung des Verk&auml;ufers.<\/p>\n\n<h2>4) Preise und Zahlungsbedingungen<\/h2>\n\n<p><b>4.1<\/b>&nbsp;Sofern sich aus der Produktbeschreibung des Verk&auml;ufers nichts anderes ergibt, handelt es sich bei den angegebenen Preisen um Gesamtpreise, die die gesetzliche Umsatzsteuer enthalten. Gegebenenfalls zus&auml;tzlich anfallende Liefer- und Versandkosten werden in der jeweiligen Produktbeschreibung gesondert angegeben.<\/p>\n\n<p><b>4.2<\/b>&nbsp;Die Zahlungsm&ouml;glichkeit\/en wird\/werden dem Kunden im Online-Shop des Verk&auml;ufers mitgeteilt.<\/p>\n\n<p><b>4.3<\/b>&nbsp;Ist Vorauskasse per Bank&uuml;berweisung vereinbart, ist die Zahlung sofort nach Vertragsabschluss f&auml;llig, sofern die Parteien keinen sp&auml;teren F&auml;lligkeitstermin vereinbart haben.<\/p>\n\n<p><b>4.4<\/b>&nbsp;Bei Auswahl der Zahlungsart Rechnungskauf wird der Kaufpreis f&auml;llig, nachdem die Ware geliefert und in Rechnung gestellt wurde. In diesem Fall ist der Kaufpreis innerhalb von 14 (vierzehn) Tagen ab Erhalt der Rechnung ohne Abzug zu zahlen, sofern nichts anderes vereinbart ist. Der Verk&auml;ufer beh&auml;lt sich vor, die Zahlungsart Rechnungskauf nur bis zu einem bestimmten Bestellvolumen anzubieten und diese Zahlungsart bei &Uuml;berschreitung des angegebenen Bestellvolumens abzulehnen. In diesem Fall wird der Verk&auml;ufer den Kunden in seinen Zahlungsinformationen im Online-Shop auf eine entsprechende Zahlungsbeschr&auml;nkung hinweisen. Der Verk&auml;ufer beh&auml;lt sich ferner vor, bei Auswahl der Zahlungsart Rechnungskauf eine Bonit&auml;tspr&uuml;fung durchzuf&uuml;hren und diese Zahlungsart bei negativer Bonit&auml;tspr&uuml;fung abzulehnen.<\/p>\n\n<p><b>4.5<\/b>&nbsp;Bei Auswahl der Zahlungsart Rechnungskauf wird der Kaufpreis f&auml;llig, nachdem die Ware geliefert und in Rechnung gestellt wurde. In diesem Fall ist der Kaufpreis innerhalb von 7 (sieben) Tagen ab Erhalt der Rechnung ohne Abzug zu zahlen, sofern nichts anderes vereinbart ist. Der Verk&auml;ufer beh&auml;lt sich vor, die Zahlungsart Rechnungskauf nur bis zu einem bestimmten Bestellvolumen anzubieten und diese Zahlungsart bei &Uuml;berschreitung des angegebenen Bestellvolumens abzulehnen. In diesem Fall wird der Verk&auml;ufer den Kunden in seinen Zahlungsinformationen im Online-Shop auf eine entsprechende Zahlungsbeschr&auml;nkung hinweisen. Der Verk&auml;ufer beh&auml;lt sich ferner vor, bei Auswahl der Zahlungsart Rechnungskauf eine Bonit&auml;tspr&uuml;fung durchzuf&uuml;hren und diese Zahlungsart bei negativer Bonit&auml;tspr&uuml;fung abzulehnen.<\/p>\n\n<p><b>4.6<\/b>&nbsp;Bei Auswahl der Zahlungsart Rechnungskauf wird der Kaufpreis f&auml;llig, nachdem die Ware geliefert und in Rechnung gestellt wurde. In diesem Fall ist der Kaufpreis innerhalb von 14 (vierzehn) Tagen ab Erhalt der Rechnung ohne Abzug zu zahlen, sofern nichts anderes vereinbart ist. Der Verk&auml;ufer beh&auml;lt sich vor, die Zahlungsart Rechnungskauf nur bis zu einem bestimmten Bestellvolumen anzubieten und diese Zahlungsart bei &Uuml;berschreitung des angegebenen Bestellvolumens abzulehnen. In diesem Fall wird der Verk&auml;ufer den Kunden in seinen Zahlungsinformationen im Online-Shop auf eine entsprechende Zahlungsbeschr&auml;nkung hinweisen.<\/p>\n\n<p><b>4.7<\/b>&nbsp;Bei Auswahl der Zahlungsart Rechnungskauf wird der Kaufpreis f&auml;llig, nachdem die Ware geliefert und in Rechnung gestellt wurde. In diesem Fall ist der Kaufpreis innerhalb von 7 (sieben) Tagen ab Erhalt der Rechnung ohne Abzug zu zahlen, sofern nichts anderes vereinbart ist. Der Verk&auml;ufer beh&auml;lt sich vor, die Zahlungsart Rechnungskauf nur bis zu einem bestimmten Bestellvolumen anzubieten und diese Zahlungsart bei &Uuml;berschreitung des angegebenen Bestellvolumens abzulehnen. In diesem Fall wird der Verk&auml;ufer den Kunden in seinen Zahlungsinformationen im Online-Shop auf eine entsprechende Zahlungsbeschr&auml;nkung hinweisen.<\/p>\n\n<h2>5) Liefer- und Versandbedingungen<\/h2>\n\n<p><b>5.1<\/b>&nbsp;Bietet der Verk&auml;ufer den Versand der Ware an, so erfolgt die Lieferung innerhalb des vom Verk&auml;ufer angegebenen Liefergebietes an die vom Kunden angegebene Lieferanschrift, sofern nichts anderes vereinbart ist. Bei der Abwicklung der Transaktion ist die in der Bestellabwicklung des Verk&auml;ufers angegebene Lieferanschrift ma&szlig;geblich.<\/p>\n\n<p><b>5.2<\/b>&nbsp;Scheitert die Zustellung der Ware aus Gr&uuml;nden, die der Kunde zu vertreten hat, tr&auml;gt der Kunde die dem Verk&auml;ufer hierdurch entstehenden angemessenen Kosten. Dies gilt im Hinblick auf die Kosten f&uuml;r die Hinsendung nicht, wenn der Kunde sein Widerrufsrecht wirksam aus&uuml;bt. F&uuml;r die R&uuml;cksendekosten gilt bei wirksamer Aus&uuml;bung des Widerrufsrechts durch den Kunden die in der Widerrufsbelehrung des Verk&auml;ufers hierzu getroffene Regelung.<\/p>\n\n<p><b>5.3<\/b>&nbsp;Handelt der Kunde als Unternehmer, geht die Gefahr des zuf&auml;lligen Untergangs und der zuf&auml;lligen Verschlechterung der verkauften Ware auf den Kunden &uuml;ber, sobald der Verk&auml;ufer die Sache dem Spediteur, dem Frachtf&uuml;hrer oder der sonst zur Ausf&uuml;hrung der Versendung bestimmten Person oder Anstalt ausgeliefert hat. Handelt der Kunde als Verbraucher, geht die Gefahr des zuf&auml;lligen Untergangs und der zuf&auml;lligen Verschlechterung der verkauften Ware grunds&auml;tzlich erst mit &Uuml;bergabe der Ware an den Kunden oder eine empfangsberechtigte Person &uuml;ber. Abweichend hiervon geht die Gefahr des zuf&auml;lligen Untergangs und der zuf&auml;lligen Verschlechterung der verkauften Ware auch bei Verbrauchern bereits auf den Kunden &uuml;ber, sobald der Verk&auml;ufer die Sache dem Spediteur, dem Frachtf&uuml;hrer oder der sonst zur Ausf&uuml;hrung der Versendung bestimmten Person oder Anstalt ausgeliefert hat, wenn der Kunde den Spediteur, den Frachtf&uuml;hrer oder die sonst zur Ausf&uuml;hrung der Versendung bestimmte Person oder Anstalt mit der Ausf&uuml;hrung beauftragt und der Verk&auml;ufer dem Kunden diese Person oder Anstalt zuvor nicht benannt hat.<\/p>\n\n<p><b>5.4<\/b>&nbsp;Handelt der Kunde als Verbraucher mit Sitz in Deutschland oder als Unternehmer, beh&auml;lt sich der Verk&auml;ufer das Recht vor, im Falle nicht richtiger oder nicht ordnungsgem&auml;&szlig;er Selbstbelieferung vom Vertrag zur&uuml;ckzutreten. Dies gilt jedoch nur f&uuml;r den Fall, dass die Nichtlieferung nicht vom Verk&auml;ufer zu vertreten ist und dieser mit der gebotenen Sorgfalt ein konkretes Deckungsgesch&auml;ft mit dem Zulieferer abgeschlossen hat. Der Verk&auml;ufer wird alle zumutbaren Anstrengungen unternehmen, um die Ware zu beschaffen. Im Falle der Nichtverf&uuml;gbarkeit oder der nur teilweisen Verf&uuml;gbarkeit der Ware wird der Kunde unverz&uuml;glich informiert und die Gegenleistung unverz&uuml;glich erstattet.<\/p>\n\n<p><b>5.5<\/b>&nbsp;Selbstabholung ist aus logistischen Gr&uuml;nden nicht m&ouml;glich.<\/p>\n\n<p><b>5.6<\/b>&nbsp;Gutscheine werden dem Kunden wie folgt bereitgestellt:<\/p>\n\n<ul>\n<li>per Download<\/li>\n<li>per E-Mail<\/li>\n<li>postalisch<\/li>\n<\/ul>\n\n<p><b>5.7<\/b>&nbsp;Digitale Inhalte werden dem Kunden wie folgt bereitgestellt:<\/p>\n\n<ul>\n<li>per Download<\/li>\n<li>per E-Mail<\/li>\n<\/ul>\n\n<h2>6) Einr&auml;umung von Nutzungsrechten f&uuml;r digitale Inhalte<\/h2>\n\n<p><b>6.1<\/b>&nbsp;Sofern sich aus der Inhaltsbeschreibung im Online-Shop des Verk&auml;ufers nichts anderes ergibt, r&auml;umt der Verk&auml;ufer dem Kunden an den bereitgestellten Inhalten das nicht ausschlie&szlig;liche, &ouml;rtlich und zeitlich unbeschr&auml;nkte Recht ein, die Inhalte zu privaten sowie zu kommerziellen Zwecken zu nutzen.<\/p>\n\n<p><b>6.2<\/b>&nbsp;Eine Weitergabe der Inhalte an Dritte oder die Erstellung von Kopien f&uuml;r Dritte au&szlig;erhalb des Rahmens dieser AGB ist nicht gestattet, soweit nicht der Verk&auml;ufer einer &Uuml;bertragung der vertragsgegenst&auml;ndlichen Lizenz an den Dritten zugestimmt hat.<\/p>\n\n<p><b>6.3<\/b>&nbsp;Soweit sich der Vertrag auf die einmalige Bereitstellung eines digitalen Inhalts bezieht, wird die Rechtseinr&auml;umung erst wirksam, wenn der Kunde die geschuldete Verg&uuml;tung vollst&auml;ndig geleistet hat. Der Verk&auml;ufer kann eine Benutzung der vertragsgegenst&auml;ndlichen Inhalte auch schon vor diesem Zeitpunkt vorl&auml;ufig erlauben. Ein &Uuml;bergang der Rechte findet durch eine solche vorl&auml;ufige Erlaubnis nicht statt.<\/p>\n\n<h2>7) Vertragsdauer und Vertragsbeendigung bei Abonnementvertr&auml;gen f&uuml;r Waren<\/h2>\n\n<p><b>7.1<\/b>&nbsp;Abonnementvertr&auml;ge werden unbefristet, mindestens jedoch f&uuml;r die aus der jeweiligen Produktbeschreibung im Online-Shop des Verk&auml;ufers ersichtliche Mindestlaufzeit geschlossen. Der Abonnementvertrag kann w&auml;hrend der Mindestlaufzeit mit einer K&uuml;ndigungsfrist von einem Monat zum Ende der Mindestlaufzeit und nach Ablauf der Mindestlaufzeit jederzeit mit einer K&uuml;ndigungsfrist von einem Monat gek&uuml;ndigt werden.<\/p>\n\n<p><b>7.2<\/b>&nbsp;Das Recht zur au&szlig;erordentlichen K&uuml;ndigung aus wichtigem Grund bleibt unber&uuml;hrt. Ein wichtiger Grund liegt vor, wenn dem k&uuml;ndigenden Teil unter Ber&uuml;cksichtigung aller Umst&auml;nde des Einzelfalls und unter Abw&auml;gung der beiderseitigen Interessen die Fortsetzung des Vertragsverh&auml;ltnisses bis zur vereinbarten Beendigung oder bis zum Ablauf einer K&uuml;ndigungsfrist nicht zugemutet werden kann.<\/p>\n\n<p><b>7.3<\/b>&nbsp;K&uuml;ndigungen k&ouml;nnen schriftlich, in Textform (z. B. per E-Mail) oder in elektronischer Form &uuml;ber die vom Verk&auml;ufer auf seiner Website vorgehaltene K&uuml;ndigungsvorrichtung (K&uuml;ndigungsbutton) erfolgen.<\/p>\n\n<h2>8) Vertragsdauer und Vertragsbeendigung bei Abonnementvertr&auml;gen f&uuml;r digitale Inhalte<\/h2>\n\n<p><b>8.1<\/b>&nbsp;Das Recht zur au&szlig;erordentlichen K&uuml;ndigung aus wichtigem Grund bleibt unber&uuml;hrt. Ein wichtiger Grund liegt vor, wenn dem k&uuml;ndigenden Teil unter Ber&uuml;cksichtigung aller Umst&auml;nde des Einzelfalls und unter Abw&auml;gung der beiderseitigen Interessen die Fortsetzung des Vertragsverh&auml;ltnisses bis zur vereinbarten Beendigung oder bis zum Ablauf einer K&uuml;ndigungsfrist nicht zugemutet werden kann.<\/p>\n\n<p><b>8.2<\/b>&nbsp;K&uuml;ndigungen k&ouml;nnen schriftlich, in Textform (z. B. per E-Mail) oder in elektronischer Form &uuml;ber die vom Verk&auml;ufer auf seiner Website vorgehaltene K&uuml;ndigungsvorrichtung (K&uuml;ndigungsbutton) erfolgen.<\/p>\n\n<h2>9) Eigentumsvorbehalt<\/h2>\n\n<p>Tritt der Verk&auml;ufer in Vorleistung, beh&auml;lt er sich bis zur vollst&auml;ndigen Bezahlung des geschuldeten Kaufpreises das Eigentum an der gelieferten Ware vor.<\/p>\n\n<h2>10) M&auml;ngelhaftung (Gew&auml;hrleistung)<\/h2>\n\n<p>Soweit sich aus den nachfolgenden Regelungen nichts anderes ergibt, gelten die Vorschriften der gesetzlichen M&auml;ngelhaftung. Hiervon abweichend gilt bei Vertr&auml;gen zur Lieferung von Waren:<\/p>\n\n<p><b>10.1<\/b>&nbsp;Handelt der Kunde als Unternehmer,<\/p>\n\n<ul>\n<li>hat der Verk&auml;ufer die Wahl der Art der Nacherf&uuml;llung;<\/li>\n<li>betr&auml;gt bei neuen Waren die Verj&auml;hrungsfrist f&uuml;r M&auml;ngelrechte ein Jahr ab Ablieferung der Ware;<\/li>\n<li>sind bei gebrauchten Waren die M&auml;ngelrechte ausgeschlossen;<\/li>\n<li>beginnt die Verj&auml;hrung nicht erneut, wenn im Rahmen der M&auml;ngelhaftung eine Ersatzlieferung erfolgt.<\/li>\n<\/ul>\n\n<p><b>10.2<\/b>&nbsp;Handelt der Kunde als Verbraucher gilt bei Vertr&auml;gen zur Lieferung gebrauchter Waren mit der Einschr&auml;nkung der nachfolgenden Ziffer: Die Verj&auml;hrungsfrist f&uuml;r M&auml;ngelanspr&uuml;che betr&auml;gt ein Jahr ab Ablieferung der Ware, wenn dies zwischen den Parteien ausdr&uuml;cklich und gesondert vertraglich vereinbart wurde und der Kunde vor der Abgabe seiner Vertragserkl&auml;rung von der Verk&uuml;rzung der Verj&auml;hrungsfrist eigens in Kenntnis gesetzt wurde.<\/p>\n\n<p><b>10.3<\/b>&nbsp;Die vorstehend geregelten Haftungsbeschr&auml;nkungen und Fristverk&uuml;rzungen gelten nicht<\/p>\n\n<ul>\n<li>f&uuml;r Schadensersatz- und Aufwendungsersatzanspr&uuml;che des Kunden,<\/li>\n<li>f&uuml;r den Fall, dass der Verk&auml;ufer den Mangel arglistig verschwiegen hat,<\/li>\n<li>f&uuml;r Waren, die entsprechend ihrer &uuml;blichen Verwendungsweise f&uuml;r ein Bauwerk verwendet worden sind und dessen Mangelhaftigkeit verursacht haben,<\/li>\n<li>f&uuml;r eine ggf. bestehende Verpflichtung des Verk&auml;ufers zur Bereitstellung von Aktualisierungen f&uuml;r digitale Produkte, bei Vertr&auml;gen zur Lieferung von Waren mit digitalen Elementen.<\/li>\n<\/ul>\n\n<p><b>10.4<\/b>&nbsp;Dar&uuml;ber hinaus gilt f&uuml;r Unternehmer, dass die gesetzlichen Verj&auml;hrungsfristen f&uuml;r einen ggf. bestehenden gesetzlichen R&uuml;ckgriffsanspruch unber&uuml;hrt bleiben.<\/p>\n\n<p><b>10.5<\/b>&nbsp;Handelt der Kunde als Kaufmann i.S.d. &sect; 1 HGB, trifft ihn die kaufm&auml;nnische Untersuchungs- und R&uuml;gepflicht gem&auml;&szlig; &sect; 377 HGB. Unterl&auml;sst der Kunde die dort geregelten Anzeigepflichten, gilt die Ware als genehmigt.<\/p>\n\n<p><b>10.6<\/b>&nbsp;Handelt der Kunde als Verbraucher, so wird er gebeten, angelieferte Waren mit offensichtlichen Transportsch&auml;den bei dem Zusteller zu reklamieren und den Verk&auml;ufer hiervon in Kenntnis zu setzen. Kommt der Kunde dem nicht nach, hat dies keinerlei Auswirkungen auf seine gesetzlichen oder vertraglichen M&auml;ngelanspr&uuml;che.<\/p>\n\n<p><b>10.7<\/b>&nbsp;Der Verk&auml;ufer haftet nicht f&uuml;r M&auml;ngel bei der Durchf&uuml;hrung des Telekommunikationsvertrages, f&uuml;r die ausschlie&szlig;lich der jeweilige Serviceprovider verantwortlich ist. Insoweit gelten die entsprechenden gesetzlichen Bestimmungen sowie ggf. hiervon abweichende Vertragsbedingungen des jeweiligen Serviceproviders.<\/p>\n\n<h2>11) Haftung<\/h2>\n\n<p>Der Verk&auml;ufer haftet dem Kunden aus allen vertraglichen, vertrags&auml;hnlichen und gesetzlichen, auch deliktischen Anspr&uuml;chen auf Schadens- und Aufwendungsersatz wie folgt:<\/p>\n\n<p><b>11.1<\/b>&nbsp;Der Verk&auml;ufer haftet aus jedem Rechtsgrund uneingeschr&auml;nkt<\/p>\n\n<ul>\n<li>bei Vorsatz oder grober Fahrl&auml;ssigkeit,<\/li>\n<li>bei vors&auml;tzlicher oder fahrl&auml;ssiger Verletzung des Lebens, des K&ouml;rpers oder der Gesundheit,<\/li>\n<li>aufgrund eines Garantieversprechens, soweit diesbez&uuml;glich nichts anderes geregelt ist,<\/li>\n<li>aufgrund zwingender Haftung wie etwa nach dem Produkthaftungsgesetz.<\/li>\n<\/ul>\n\n<p><b>11.2<\/b>&nbsp;Handelt der Kunde als Verbraucher mit Sitz in Deutschland oder als Unternehmer, gelten folgende Haftungsbeschr&auml;nkungen:<\/p>\n\n<p>Verletzt der Verk&auml;ufer fahrl&auml;ssig eine wesentliche Vertragspflicht, ist seine Haftung auf den vertragstypischen, vorhersehbaren Schaden begrenzt, sofern er nicht gem&auml;&szlig; vorstehender Ziffer unbeschr&auml;nkt haftet. Wesentliche Vertragspflichten sind Pflichten, die der Vertrag dem Verk&auml;ufer nach seinem Inhalt zur Erreichung des Vertragszwecks auferlegt, deren Erf&uuml;llung die ordnungsgem&auml;&szlig;e Durchf&uuml;hrung des Vertrags &uuml;berhaupt erst erm&ouml;glicht und auf deren Einhaltung der Kunde regelm&auml;&szlig;ig vertrauen darf. Im &Uuml;brigen ist eine Haftung des Verk&auml;ufers ausgeschlossen, sofern er nicht gem&auml;&szlig; vorstehender Ziffer unbeschr&auml;nkt haftet.<\/p>\n\n<p><b>11.3<\/b>&nbsp;Vorstehende Haftungsregelungen gelten auch im Hinblick auf die Haftung des Verk&auml;ufers f&uuml;r seine Erf&uuml;llungsgehilfen und gesetzlichen Vertreter.<\/p>\n\n<h2>12) Besondere Bedingungen f&uuml;r die Verarbeitung von Waren nach bestimmten Vorgaben des Kunden<\/h2>\n\n<p><b>12.1<\/b>&nbsp;Schuldet der Verk&auml;ufer nach dem Inhalt des Vertrages neben der Warenlieferung auch die Verarbeitung der Ware nach bestimmten Vorgaben des Kunden, hat der Kunde dem Verk&auml;ufer alle f&uuml;r die Verarbeitung erforderlichen Inhalte wie Texte, Bilder oder Grafiken in den vom Verk&auml;ufer vorgegebenen Dateiformaten, Formatierungen, Bild- und Dateigr&ouml;&szlig;en zur Verf&uuml;gung zu stellen und ihm die hierf&uuml;r erforderlichen Nutzungsrechte einzur&auml;umen. F&uuml;r die Beschaffung und den Rechteerwerb an diesen Inhalten ist allein der Kunde verantwortlich. Der Kunde erkl&auml;rt und &uuml;bernimmt die Verantwortung daf&uuml;r, dass er das Recht besitzt, die dem Verk&auml;ufer &uuml;berlassenen Inhalte zu nutzen. Er tr&auml;gt insbesondere daf&uuml;r Sorge, dass hierdurch keine Rechte Dritter verletzt werden, insbesondere Urheber-, Marken- und Pers&ouml;nlichkeitsrechte.<\/p>\n\n<p><b>12.2<\/b>&nbsp;Der Kunde stellt den Verk&auml;ufer von Anspr&uuml;chen Dritter frei, die diese im Zusammenhang mit einer Verletzung ihrer Rechte durch die vertragsgem&auml;&szlig;e Nutzung der Inhalte des Kunden durch den Verk&auml;ufer diesem gegen&uuml;ber geltend machen k&ouml;nnen. Der Kunde &uuml;bernimmt hierbei auch die notwendigen Kosten der Rechtsverteidigung einschlie&szlig;lich aller Gerichts- und Anwaltskosten in gesetzlicher H&ouml;he. Dies gilt nicht, wenn die Rechtsverletzung vom Kunden nicht zu vertreten ist. Der Kunde ist verpflichtet, dem Verk&auml;ufer im Falle einer Inanspruchnahme durch Dritte unverz&uuml;glich, wahrheitsgem&auml;&szlig; und vollst&auml;ndig alle Informationen zur Verf&uuml;gung zu stellen, die f&uuml;r die Pr&uuml;fung der Anspr&uuml;che und eine Verteidigung erforderlich sind.<\/p>\n\n<p><b>12.3<\/b>&nbsp;Der Verk&auml;ufer beh&auml;lt sich vor, Verarbeitungsauftr&auml;ge abzulehnen, wenn die vom Kunden hierf&uuml;r &uuml;berlassenen Inhalte gegen gesetzliche oder beh&ouml;rdliche Verbote oder gegen die guten Sitten verstossen. Dies gilt insbesondere bei &Uuml;berlassung verfassungsfeindlicher, rassistischer, fremdenfeindlicher, diskriminierender, beleidigender, Jugend gef&auml;hrdender und\/oder Gewalt verherrlichender Inhalte.<\/p>\n\n<h2>13) Einl&ouml;sung von Aktionsgutscheinen<\/h2>\n\n<p><b>13.1<\/b>&nbsp;Gutscheine, die vom Verk&auml;ufer im Rahmen von Werbeaktionen mit einer bestimmten G&uuml;ltigkeitsdauer unentgeltlich ausgegeben werden und die vom Kunden nicht k&auml;uflich erworben werden k&ouml;nnen (nachfolgend &quot;Aktionsgutscheine&quot;), k&ouml;nnen nur im Online-Shop des Verk&auml;ufers und nur im angegebenen Zeitraum eingel&ouml;st werden.<\/p>\n\n<p><b>13.2<\/b>&nbsp;Einzelne Produkte k&ouml;nnen von der Gutscheinaktion ausgeschlossen sein, sofern sich eine entsprechende Einschr&auml;nkung aus dem Inhalt des Aktionsgutscheins ergibt.<\/p>\n\n<p><b>13.3<\/b>&nbsp;Aktionsgutscheine k&ouml;nnen nur vor Abschluss des Bestellvorgangs eingel&ouml;st werden. Eine nachtr&auml;gliche Verrechnung ist nicht m&ouml;glich.<\/p>\n\n<p><b>13.4<\/b>&nbsp;Pro Bestellung kann immer nur ein Aktionsgutschein eingel&ouml;st werden.<\/p>\n\n<p><b>13.5<\/b>&nbsp;Sofern sich der Aktionsgutschein auf einen konkreten Wert und nicht auf einen prozentualen Preisnachlass bezieht, muss der Warenwert mindestens dem Betrag des Aktionsgutscheins entsprechen. Etwaiges Restguthaben wird vom Verk&auml;ufer nicht erstattet.<\/p>\n\n<p><b>13.6<\/b>&nbsp;Reicht der Wert des Aktionsgutscheins zur Deckung der Bestellung nicht aus, kann zur Begleichung des Differenzbetrages eine der &uuml;brigen vom Verk&auml;ufer angebotenen Zahlungsarten gew&auml;hlt werden.<\/p>\n\n<p><b>13.7<\/b>&nbsp;Das Guthaben eines Aktionsgutscheins wird weder in Bargeld ausgezahlt noch verzinst.<\/p>\n\n<p><b>13.8<\/b>&nbsp;Der Aktionsgutschein wird nicht erstattet, wenn der Kunde die mit dem Aktionsgutschein ganz oder teilweise bezahlte Ware im Rahmen seines gesetzlichen Widerrufsrechts zur&uuml;ckgibt.<\/p>\n\n<p><b>13.9<\/b>&nbsp;Der Aktionsgutschein ist nur f&uuml;r die Verwendung durch die auf ihm benannte Person bestimmt. Eine &Uuml;bertragung des Aktionsgutscheins auf Dritte ist ausgeschlossen. Der Verk&auml;ufer ist berechtigt, jedoch nicht verpflichtet, die materielle Anspruchsberechtigung des jeweiligen Gutscheininhabers zu pr&uuml;fen.<\/p>\n\n<h2>14) Einl&ouml;sung von Geschenkgutscheinen<\/h2>\n\n<p><b>14.1<\/b>&nbsp;Gutscheine, die &uuml;ber den Online-Shop des Verk&auml;ufers k&auml;uflich erworben werden k&ouml;nnen (nachfolgend &quot;Geschenkgutscheine&quot;), k&ouml;nnen nur im Online-Shop des Verk&auml;ufers eingel&ouml;st werden, sofern sich aus dem Gutschein nichts anderes ergibt.<\/p>\n\n<p><b>14.2<\/b>&nbsp;Geschenkgutscheine und Restguthaben von Geschenkgutscheinen sind bis zum Ende des dritten Jahres nach dem Jahr des Gutscheinkaufs einl&ouml;sbar. Restguthaben werden dem Kunden bis zum Ablaufdatum gutgeschrieben.<\/p>\n\n<p><b>14.3<\/b>&nbsp;Geschenkgutscheine k&ouml;nnen nur vor Abschluss des Bestellvorgangs eingel&ouml;st werden. Eine nachtr&auml;gliche Verrechnung ist nicht m&ouml;glich.<\/p>\n\n<p><b>14.4<\/b>&nbsp;Geschenkgutscheine k&ouml;nnen nur f&uuml;r den Kauf von Waren und nicht f&uuml;r den Kauf von weiteren Geschenkgutscheinen verwendet werden.<\/p>\n\n<p><b>14.5<\/b>&nbsp;Reicht der Wert des Geschenkgutscheins zur Deckung der Bestellung nicht aus, kann zur Begleichung des Differenzbetrages eine der &uuml;brigen vom Verk&auml;ufer angebotenen Zahlungsarten gew&auml;hlt werden.<\/p>\n\n<p><b>14.6<\/b>&nbsp;Das Guthaben eines Geschenkgutscheins wird weder in Bargeld ausgezahlt noch verzinst.<\/p>\n\n<p><b>14.7<\/b>&nbsp;Der Geschenkgutschein ist &uuml;bertragbar. Der Verk&auml;ufer kann mit befreiender Wirkung an den jeweiligen Inhaber, der den Geschenkgutschein im Online-Shop des Verk&auml;ufers einl&ouml;st, leisten. Dies gilt nicht, wenn der Verk&auml;ufer Kenntnis oder grob fahrl&auml;ssige Unkenntnis von der Nichtberechtigung, der Gesch&auml;ftsunf&auml;higkeit oder der fehlenden Vertretungsberechtigung des jeweiligen Inhabers hat.<\/p>\n\n<h2>15) Anwendbares Recht<\/h2>\n\n<p>F&uuml;r s&auml;mtliche Rechtsbeziehungen der Parteien gilt das Recht der Bundesrepublik Deutschland unter Ausschluss der Gesetze &uuml;ber den internationalen Kauf beweglicher Waren. Bei Verbrauchern gilt diese Rechtswahl nur insoweit, als nicht der durch zwingende Bestimmungen des Rechts des Staates, in dem der Verbraucher seinen gew&ouml;hnlichen Aufenthalt hat, gew&auml;hrte Schutz entzogen wird.<\/p>\n\n<h2>16) Verhaltenskodex<\/h2>\n\n<ul>\n<li>Der Verk&auml;ufer hat sich den Teilnahmebedingungen f&uuml;r die eCommerce-Initiative &bdquo;Fairness im Handel&#8220; unterworfen, die im Internet unter <a href=\"https:\/\/www.fairness-im-handel.de\/teilnahmebedingungen\/\" target=\"_blank\">https:\/\/www.fairness-im-handel.de<wbr>\/teilnahmebedingungen<wbr>\/<\/a> einsehbar sind.<\/li>\n<li>Der Verk&auml;ufer hat sich den Richtlinien f&uuml;r &bdquo;Google Kundenrezensionen&#8220; unterworfen, die im Internet unter <a href=\"https:\/\/support.google.com\/merchants\/answer\/14629803?hl=de&amp;ref_topic=14629086\" target=\"_blank\">https:\/\/support.google.com<wbr>\/merchants<wbr>\/answer<wbr>\/14629803<wbr>?hl=de<wbr>&amp;ref_topic=14629086<\/a> einsehbar sind.<\/li>\n<\/ul>\n\n<h2>17) Alternative Streitbeilegung<\/h2>\n\n<p>Der Verk&auml;ufer ist zur Teilnahme an einem Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle nicht verpflichtet, hierzu aber bereit.<\/p><\/div><div id=\"itkanzlei_txt_copyright\" style=\"font-size: 12px; margin-top: 8em;\"><div style=\"display: inline-block; vertical-align: top;\"><a href=\"https:\/\/www.it-recht-kanzlei.de\/\" target=\"_blank\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.it-recht-kanzlei.de\/logo\/Copyright-Logo_AGB.png?w=800&#038;ssl=1\" id=\"itkanzlei_img_copyright\" alt=\"&copy; IT-Recht Kanzlei\" title=\"&copy; IT-Recht Kanzlei\" style=\"margin-top: -20px; border-style: none; max-width: 100%;\" \/><\/a><\/div><div style=\"display: inline-block; vertical-align: top; margin-left: 5px; float: right; white-space: nowrap;\">Stand: 15.07.2026, 04:10:51<\/div><div style=\"clear: right;\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"class_list":["post-780","page","type-page","status-publish","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/PbgHd5-cA","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/abicos.de\/cms\/wp-json\/wp\/v2\/pages\/780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abicos.de\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/abicos.de\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/abicos.de\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/abicos.de\/cms\/wp-json\/wp\/v2\/comments?post=780"}],"version-history":[{"count":23,"href":"https:\/\/abicos.de\/cms\/wp-json\/wp\/v2\/pages\/780\/revisions"}],"predecessor-version":[{"id":1382,"href":"https:\/\/abicos.de\/cms\/wp-json\/wp\/v2\/pages\/780\/revisions\/1382"}],"wp:attachment":[{"href":"https:\/\/abicos.de\/cms\/wp-json\/wp\/v2\/media?parent=780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}